{"id":5509,"date":"2023-10-11T11:20:54","date_gmt":"2023-10-11T09:20:54","guid":{"rendered":"https:\/\/die-wetterversicherung.de\/blog\/?p=5509"},"modified":"2023-10-11T11:45:25","modified_gmt":"2023-10-11T09:45:25","slug":"studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter","status":"publish","type":"post","link":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/","title":{"rendered":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema <\/strong><strong>Insektensterben <\/strong><strong>vom \u201cSchuldigen\u201d zum Helfer.<\/strong><\/h4>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"596\" src=\"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten-1024x596.jpg\" alt=\"eine biene saugt an einer blume nektar\" class=\"wp-image-5510\" srcset=\"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten-1024x596.jpg 1024w, https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten-300x175.jpg 300w, https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten-768x447.jpg 768w, https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten-750x437.jpg 750w, https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Foto: mariya_m\/Pixabay.com<\/figcaption><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Forscher schreiben das Insektensterben auch dem Wetter zu<\/li>\n\n\n\n<li>Insekten reagieren auf anormale Witterung<\/li>\n\n\n\n<li>Ma\u00dfnahmen gegen das wetterbedingte Insektensterben<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Das Insektensterben wird in vielen Studien zu einem Gro\u00dfteil Landwirten beziehungsweise den verwendeten Pestiziden zugeschrieben. Doch laut einer neuen Studie der <a href=\"https:\/\/www.uni-wuerzburg.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Universit\u00e4t W\u00fcrzburg<\/a> <strong>liegt die Entwicklung auch am Wetter<\/strong> und das zu einem nicht unerheblichen Teil.\u00a0<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Insekten reagieren auf anormale Witterung<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Insekten reagieren den Wissenschaftlern zufolge empfindlich, wenn <strong>Temperatur und Niederschl\u00e4ge vom langj\u00e4hrigen Mittel abweichen<\/strong>. Bei einem ungew\u00f6hnlich trockenen und warmen Winter ist die Wahrscheinlichkeit, dass sie \u00fcberleben, verringert. Bei einem nasskalten Fr\u00fchjahr ist der Schlupferfolg reduziert. Ein k\u00fchler, feuchter Sommer <strong>setzt Hummeln und andere Fluginsekten bei der Fortpflanzung und der <\/strong><strong>Nahrungssuche<\/strong><strong> unter Druck<\/strong>. Treten mehrere solcher Witterungs-Anomalien in Kombination und \u00fcber mehrere Jahre auf, kann dies die Insektenbiomasse gro\u00dfr\u00e4umig und langfristig reduzieren. Demnach k\u00f6nnen die Witterung und H\u00e4ufungen ung\u00fcnstiger Witterungsanomalien im Zuge des Klimawandels wichtige Treiber des weltweiten Insektensterbens sein.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Ma\u00dfnahmen gegen das wetterbedingte <\/strong><strong>Insektensterben<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Um das Aussterberisiko bedrohter Arten unter diesen Rahmenbedingungen abzuschw\u00e4chen, fordern die Wissenschaftler, <strong>die Fl\u00e4chen hochwertiger Lebensr\u00e4ume zu vergr\u00f6\u00dfern<\/strong>. Laut den Forschern betrifft diese Gemeinschaftsaufgabe nicht nur die Landwirtschaft, sondern auch Verkehrs- und Siedlungsr\u00e4ume \u2013 also alle Gebiete, in denen hochwertige Lebensr\u00e4ume reduziert oder beeintr\u00e4chtigt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":5,"featured_media":5510,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lasst-uns-ubers-wetter-reden","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de<\/title>\n<meta name=\"description\" content=\"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de\" \/>\n<meta property=\"og:description\" content=\"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/\" \/>\n<meta property=\"og:site_name\" content=\"die-wetterversicherung.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/diewetterversicherung\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-11T09:20:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T09:45:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/#\\\/schema\\\/person\\\/ece359d1fb2756d4f371d523c75b881a\"},\"headline\":\"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter\",\"datePublished\":\"2023-10-11T09:20:54+00:00\",\"dateModified\":\"2023-10-11T09:45:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/\"},\"wordCount\":269,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\",\"articleSection\":[\"Lasst uns \u00fcbers Wetter reden!\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/\",\"url\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/\",\"name\":\"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\",\"datePublished\":\"2023-10-11T09:20:54+00:00\",\"dateModified\":\"2023-10-11T09:45:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/#\\\/schema\\\/person\\\/ece359d1fb2756d4f371d523c75b881a\"},\"description\":\"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\",\"contentUrl\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg\",\"width\":1280,\"height\":745,\"caption\":\"Foto: mariya_m\\\/Pixabay.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/\",\"name\":\"die-wetterversicherung.de\",\"description\":\"Wetterversicherung-Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/#\\\/schema\\\/person\\\/ece359d1fb2756d4f371d523c75b881a\",\"name\":\"admin\",\"url\":\"https:\\\/\\\/die-wetterversicherung.de\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de","description":"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/","og_locale":"de_DE","og_type":"article","og_title":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de","og_description":"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.","og_url":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/","og_site_name":"die-wetterversicherung.de","article_publisher":"https:\/\/www.facebook.com\/diewetterversicherung","article_published_time":"2023-10-11T09:20:54+00:00","article_modified_time":"2023-10-11T09:45:25+00:00","og_image":[{"width":1280,"height":745,"url":"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#article","isPartOf":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/"},"author":{"name":"admin","@id":"https:\/\/die-wetterversicherung.de\/blog\/#\/schema\/person\/ece359d1fb2756d4f371d523c75b881a"},"headline":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter","datePublished":"2023-10-11T09:20:54+00:00","dateModified":"2023-10-11T09:45:25+00:00","mainEntityOfPage":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/"},"wordCount":269,"commentCount":0,"image":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#primaryimage"},"thumbnailUrl":"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg","articleSection":["Lasst uns \u00fcbers Wetter reden!"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/","url":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/","name":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter - die-wetterversicherung.de","isPartOf":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#primaryimage"},"image":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#primaryimage"},"thumbnailUrl":"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg","datePublished":"2023-10-11T09:20:54+00:00","dateModified":"2023-10-11T09:45:25+00:00","author":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/#\/schema\/person\/ece359d1fb2756d4f371d523c75b881a"},"description":"Einer aktuellen Studie zufolge reagieren Insekten empfindlich auf Anomalien bei der Witterung, die in dieser Form erst durch den Klimawandel h\u00e4ufiger auftreten. Die Landwirtschaft wird beim Thema Insektensterben vom \u201cSchuldigen\u201d zum Helfer.","breadcrumb":{"@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#primaryimage","url":"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg","contentUrl":"https:\/\/die-wetterversicherung.de\/blog\/wp-content\/uploads\/2023\/10\/bienen-inskektensterben-wetter-insekten-empfindlich-warum-sterben-insekten.jpg","width":1280,"height":745,"caption":"Foto: mariya_m\/Pixabay.com"},{"@type":"BreadcrumbList","@id":"https:\/\/die-wetterversicherung.de\/blog\/studie-insektensterben-liegt-zu-einem-nicht-unwesentlichen-teil-am-wetter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/die-wetterversicherung.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Studie: Insektensterben liegt zu einem nicht unwesentlichen Teil am Wetter"}]},{"@type":"WebSite","@id":"https:\/\/die-wetterversicherung.de\/blog\/#website","url":"https:\/\/die-wetterversicherung.de\/blog\/","name":"die-wetterversicherung.de","description":"Wetterversicherung-Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/die-wetterversicherung.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/die-wetterversicherung.de\/blog\/#\/schema\/person\/ece359d1fb2756d4f371d523c75b881a","name":"admin","url":"https:\/\/die-wetterversicherung.de\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/posts\/5509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/comments?post=5509"}],"version-history":[{"count":2,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/posts\/5509\/revisions"}],"predecessor-version":[{"id":5513,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/posts\/5509\/revisions\/5513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/media\/5510"}],"wp:attachment":[{"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/media?parent=5509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/categories?post=5509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/die-wetterversicherung.de\/blog\/wp-json\/wp\/v2\/tags?post=5509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}